{"id":79590,"date":"2020-01-18T16:49:04","date_gmt":"2020-01-18T14:49:04","guid":{"rendered":"https:\/\/gahzly.com\/product\/%d9%83%d9%88%d8%a8%d8%b1%d9%8a-%d8%b1%d9%88%d8%b2%d8%aa%d8%a9-%d8%a7%d9%88%d9%86%d9%8a%d9%83%d8%a7\/"},"modified":"2023-03-06T22:33:02","modified_gmt":"2023-03-06T20:33:02","slug":"jumper-for-terminals-onka","status":"publish","type":"product","link":"https:\/\/gahzly.com\/en\/\u0645\u0646\u062a\u062c\/jumper-for-terminals-onka\/","title":{"rendered":"jumper for terminals ONKA"},"content":{"rendered":"<h4>jumper for terminals ONKA<\/h4>\n<h4><span style=\"vertical-align: inherit\"><span class=\"\" style=\"vertical-align: inherit\">Category: Rosetta Bridge<\/span><\/span><\/h4>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43437 aligncenter\" src=\"https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0628\u0621\u0628.png\" alt=\"\" width=\"794\" height=\"465\" title=\"l\" srcset=\"https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0628\u0621\u0628.png 794w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0628\u0621\u0628-600x351.png 600w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0628\u0621\u0628-768x450.png 768w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0628\u0621\u0628-640x375.png 640w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0628\u0621\u0628-400x234.png 400w\" sizes=\"auto, (max-width: 794px) 100vw, 794px\" \/><\/h4>\n<div class=\"product-detail page-product__detail\">\n<div class=\"_3wdEZ5\">\n<div class=\"_1afiLm\">\n<h4><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Product Description :<\/span><\/span><\/h4>\n<p><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Good electrical resistance, heat resistance, fire resistance, low shrinkage and water resistance, excellent texture and fine workmanship are your choice.<\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">\u00a0High strength insulator.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Widely used in low and high power distribution cabinet.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">For power distribution, transmission, copper or aluminum busbar fixing, etc., play the role of insulation and conduction.<\/span><\/span><\/li>\n<\/ul>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43432 aligncenter\" src=\"https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0633\u0628\u0633\u0628.png\" alt=\"\" width=\"710\" height=\"526\" title=\"l\" srcset=\"https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0633\u0628\u0633\u0628.png 710w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0633\u0628\u0633\u0628-600x445.png 600w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0633\u0628\u0633\u0628-640x474.png 640w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0633\u0628\u0633\u0628-400x296.png 400w\" sizes=\"auto, (max-width: 710px) 100vw, 710px\" \/><\/h4>\n<h4><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">They are used for safe and compact delivery<\/span><\/span><\/h4>\n<ul>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">\u00a0It is passed on to the new OPK series rosette bridge system.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">In case of pin curvature and diagonal structure it can be touched 4 points to the copper busbar.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">It can be cut in the middle of the rosette bridge<\/span><\/span><\/li>\n<\/ul>\n<h4><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.gahzly.com\/wp-content\/uploads\/2020\/01\/%D9%83%D9%88%D8%A8%D8%B1%D9%8A-%D8%B1%D9%88%D8%B2%D8%AA%D8%A9-%D8%A7%D9%88%D9%86%D9%8A%D9%83%D8%A7-1.jpg\" alt=\"\" title=\"l\"><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">product specification<\/span><\/span><\/h4>\n<ul>\n<li>jumper for terminals ONKA<\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Product manufacturer: onka<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Product type: bridge rosettes<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Color: orange<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Fits 10mm &#8211; 2.5mm &#8211; 4mm &#8211; 6mm rosettes<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Materials used: polyamide and copper<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Degree of protection: IP: IP20<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Working temperature: -40 \u2014 + 140 degrees Celsius<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Long life<\/span><\/span><br \/>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-43435 aligncenter\" src=\"https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0621\u0628\u0621\u0628\u0621\u0628.png\" alt=\"\" width=\"516\" height=\"408\" title=\"l\" srcset=\"https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0621\u0628\u0621\u0628\u0621\u0628.png 362w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0621\u0628\u0621\u0628\u0621\u0628-360x286.png 360w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><\/h4>\n<\/li>\n<\/ul>\n<h4><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">An example of its use<\/span><\/span><\/h4>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43317 aligncenter\" title=\"Unika roses complete with lid colors. Unika roses complete with lid colors\" src=\"https:\/\/i0.wp.com\/www.gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-13.png?resize=807%2C381&amp;ssl=1\" alt=\"Unika rosette complete with color cover\" width=\"807\" height=\"381\" data-recalc-dims=\"1\" srcset=\"https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-13.png 807w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-13-600x283.png 600w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-13-768x363.png 768w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-13-640x302.png 640w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-13-400x189.png 400w\" sizes=\"auto, (max-width: 807px) 100vw, 807px\" \/><\/h4>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43325 aligncenter\" title=\"Unika roses complete with lid colors. Unika roses complete with lid colors\" src=\"https:\/\/i2.wp.com\/www.gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-9.png?resize=697%2C441&amp;ssl=1\" alt=\"Unika rosette complete with color cover\" width=\"697\" height=\"441\" data-recalc-dims=\"1\" srcset=\"https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-9.png 697w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-9-600x380.png 600w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-9-640x405.png 640w, https:\/\/gahzly.com\/wp-content\/uploads\/2020\/01\/\u0631\u0648\u0632\u062a\u0629-\u0627\u0648\u0646\u064a\u0643\u0627-\u0643\u0627\u0645\u0644\u0629-\u0628\u0627\u0644\u063a\u0637\u0627\u0621-\u0627\u0644\u0648\u0627\u0646-9-400x253.png 400w\" sizes=\"auto, (max-width: 697px) 100vw, 697px\" \/><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<h4><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Its advantages:<\/span><\/span><\/h4>\n<ul>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">High dielectric strength.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">High mechanical resistance.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">High heat and wet resistance<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">thermoplastic material.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">high strength<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Smooth finish<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">optimum durability<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Insulating busbars enable copper or aluminum busbars to be fixed and are tested to hold safely during a short circuit<\/span><\/span><\/li>\n<\/ul>\n<div class=\"T4LgNb\">\n<div class=\"WFnNle\">\n<div class=\"OlSOob\">\n<div class=\"ccvoYb\">\n<div class=\"AxqVh\">\n<div class=\"OPPzxe\">\n<div class=\"dePhmb\">\n<div class=\"eyKpYb\" data-language=\"ar\" data-original-language=\"auto\" data-result-index=\"0\">\n<h4><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">It is used in many applications with rosettes, for example:<\/span><\/span><\/h4>\n<ul>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Motors and generators connected to water pipe networks and pumps.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Distribution boards and key holders.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Widely used in low power, high power distribution cabinet, power distribution.<\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<h4><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Wide use<\/span><\/span><\/h4>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Quad ladder insulator Quad ladder insulator\" src=\"https:\/\/i2.wp.com\/img.everychina.com\/nimg\/bc\/d1\/f5a0ee3f1c2208540cb0e241ab9c.jpg?w=1140\" alt=\"application_.jpg\" width=\"820\" height=\"820\" data-recalc-dims=\"1\" \/><\/h4>\n<h4><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">We are pleased to have you visit our pages on social networking sites, where we publish exclusive offers on our website.<\/span><\/span><\/h4>\n<p><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Our Facebook page\u00a0 <\/span><\/span><a href=\"https:\/\/www.facebook.com\/Gahzlystore\/\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">here<\/span><\/span><\/a><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Our Twitter account\u00a0 <\/span><\/span><a href=\"https:\/\/twitter.com\/gahzly1\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">here<\/span><\/span><\/a><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\"> .<\/span><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>jumper for terminals ONKA<\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Product manufacturer: onka<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Product type: bridge rosettes<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Color: orange<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Fits 10mm &#8211; 2.5mm &#8211; 4mm &#8211; 6mm rosettes<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Materials used: polyamide and copper<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Degree of protection: IP: IP20<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Working temperature: -40 \u2014 + 140 degrees Celsius<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit\"><span style=\"vertical-align: inherit\">Long life<\/span><\/span><\/li>\n<\/ul>\n","protected":false},"featured_media":39650,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[7351,7356,7357],"product_tag":[],"class_list":{"0":"post-79590","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-circuit-breakers-and-control-devices","7":"product_cat-terminal-block","8":"product_cat-terminal-block-accessories","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/product\/79590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/comments?post=79590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/media\/39650"}],"wp:attachment":[{"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/media?parent=79590"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/product_brand?post=79590"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/product_cat?post=79590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gahzly.com\/en\/wp-json\/wp\/v2\/product_tag?post=79590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}